{"id":38081,"date":"2019-08-06T10:53:44","date_gmt":"2019-08-06T10:53:44","guid":{"rendered":"https:\/\/casaanylanzarote.com\/conditions-generales-du-gdpr\/"},"modified":"2025-08-22T00:06:47","modified_gmt":"2025-08-22T00:06:47","slug":"conditions-generales-du-gdpr","status":"publish","type":"page","link":"https:\/\/casaanylanzarote.com\/fr\/conditions-generales-du-gdpr\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales du GDPR"},"content":{"rendered":"<h1 class=\"entry-title\">Conditions g\u00e9n\u00e9rales GDPR<\/h1>\n<div class=\"single-content\">\n<h3>Qui sommes-nous ?<\/h3>\n<p>Modifiez ce contenu comme vous le souhaitez. L&rsquo;adresse de notre site web est. <\/p>\n<h3>Commentaires<\/h3>\n<p>Lorsque les visiteurs laissent des commentaires sur le site, nous recueillons les donn\u00e9es figurant dans le formulaire de commentaires, ainsi que l&rsquo;adresse IP du visiteur et la cha\u00eene de l&rsquo;agent utilisateur du navigateur afin de faciliter la d\u00e9tection des spams.<\/p>\n<p>Une cha\u00eene anonyme cr\u00e9\u00e9e \u00e0 partir de votre adresse \u00e9lectronique (\u00e9galement appel\u00e9e \u00ab\u00a0hash\u00a0\u00bb) peut \u00eatre fournie au service Gravatar pour v\u00e9rifier si vous l&rsquo;utilisez. La politique de confidentialit\u00e9 du service Gravatar est disponible ici : https:\/\/automattic.com\/privacy\/. Apr\u00e8s approbation de votre commentaire, votre photo de profil est visible par le public dans le contexte de votre commentaire. <\/p>\n<h3>Les m\u00e9dias<\/h3>\n<p>Si vous t\u00e9l\u00e9chargez des images sur le site web, vous devez \u00e9viter de t\u00e9l\u00e9charger des images contenant des donn\u00e9es de localisation int\u00e9gr\u00e9es (EXIF GPS). Les visiteurs du site web peuvent t\u00e9l\u00e9charger et extraire toutes les donn\u00e9es de localisation des images sur le site web. <\/p>\n<h3>Cookies<\/h3>\n<p>Si vous laissez un commentaire sur notre site, vous pouvez accepter que votre nom, votre adresse \u00e9lectronique et votre site web soient enregistr\u00e9s dans des cookies. Ces cookies sont destin\u00e9s \u00e0 vous faciliter la t\u00e2che, de sorte que vous n&rsquo;ayez pas \u00e0 fournir \u00e0 nouveau vos coordonn\u00e9es lorsque vous laissez un autre commentaire. Ces cookies ont une dur\u00e9e de vie d&rsquo;un an.  <\/p>\n<p>Si vous avez un compte et que vous vous connectez \u00e0 ce site, nous installerons un cookie temporaire pour d\u00e9terminer si votre navigateur accepte les cookies. Ce cookie ne contient aucune donn\u00e9e personnelle et est supprim\u00e9 lorsque vous fermez votre navigateur. <\/p>\n<p>Lorsque vous vous connectez, nous installons \u00e9galement plusieurs cookies pour enregistrer vos informations de connexion et vos choix d&rsquo;affichage \u00e0 l&rsquo;\u00e9cran. Les cookies de connexion ont une dur\u00e9e de vie de deux jours et les cookies d&rsquo;options d&rsquo;\u00e9cran ont une dur\u00e9e de vie d&rsquo;un an. Si vous s\u00e9lectionnez l&rsquo;option \u00ab\u00a0Se souvenir de moi\u00a0\u00bb, votre connexion sera conserv\u00e9e pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, les cookies de connexion seront supprim\u00e9s.   <\/p>\n<p>Si vous modifiez ou publiez un article, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne contient aucune donn\u00e9e personnelle et indique simplement l&rsquo;identifiant de l&rsquo;article que vous venez de modifier. Il expire apr\u00e8s 1 jour.  <\/p>\n<h3>Contenu int\u00e9gr\u00e9 d&rsquo;autres sites web<\/h3>\n<p>Les articles de ce site peuvent contenir du contenu int\u00e9gr\u00e9 (par exemple des vid\u00e9os, des images, des articles, etc.). Le contenu int\u00e9gr\u00e9 provenant d&rsquo;autres sites web se comporte exactement de la m\u00eame mani\u00e8re que si le visiteur avait visit\u00e9 l&rsquo;autre site web. <\/p>\n<p>Ces sites web peuvent collecter des donn\u00e9es vous concernant, utiliser des cookies, int\u00e9grer un suivi suppl\u00e9mentaire de la part de tiers et contr\u00f4ler votre interaction avec ce contenu int\u00e9gr\u00e9, y compris tracer votre interaction avec le contenu int\u00e9gr\u00e9 si vous avez un compte et \u00eates connect\u00e9 \u00e0 ce site web.<\/p>\n<h3>Dur\u00e9e de conservation des donn\u00e9es<\/h3>\n<p>Si vous laissez un commentaire, celui-ci et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela nous permet de reconna\u00eetre et d&rsquo;approuver automatiquement les commentaires de suivi au lieu de les conserver dans une file d&rsquo;attente de mod\u00e9ration. <\/p>\n<p>Pour les utilisateurs qui s&rsquo;inscrivent sur notre site web (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les informations personnelles qu&rsquo;ils fournissent dans leur profil d&rsquo;utilisateur. Tous les utilisateurs peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (sauf qu&rsquo;ils ne peuvent pas changer leur nom d&rsquo;utilisateur). Les administrateurs du site web peuvent \u00e9galement consulter et modifier ces informations.  <\/p>\n<h3>Quels sont les droits dont vous disposez sur vos donn\u00e9es ?<\/h3>\n<p>Si vous avez un compte sur ce site, ou si vous avez laiss\u00e9 des commentaires, vous pouvez demander \u00e0 recevoir un fichier export\u00e9 des donn\u00e9es personnelles que nous d\u00e9tenons \u00e0 votre sujet, y compris toutes les donn\u00e9es que vous nous avez fournies. Vous pouvez \u00e9galement nous demander d&rsquo;effacer toutes les donn\u00e9es personnelles que nous d\u00e9tenons \u00e0 votre sujet. Cela n&rsquo;inclut pas les donn\u00e9es que nous sommes oblig\u00e9s de conserver \u00e0 des fins administratives, juridiques ou de s\u00e9curit\u00e9.  <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conditions g\u00e9n\u00e9rales GDPR Qui sommes-nous ? Modifiez ce contenu comme vous le souhaitez. L&rsquo;adresse de notre site web est. Commentaires Lorsque les visiteurs laissent des commentaires sur le site, nous recueillons les donn\u00e9es figurant dans le formulaire de commentaires, ainsi que l&rsquo;adresse IP du visiteur et la cha\u00eene de l&rsquo;agent utilisateur du navigateur afin de &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"gdpr_terms.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-38081","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/pages\/38081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/comments?post=38081"}],"version-history":[{"count":0,"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/pages\/38081\/revisions"}],"wp:attachment":[{"href":"https:\/\/casaanylanzarote.com\/fr\/wp-json\/wp\/v2\/media?parent=38081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}